
{"id":118,"count":1,"description":"","link":"https:\/\/waterstream.io\/it\/category\/senza-categoria\/","name":"Senza categoria","slug":"senza-categoria","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Senza categoria Archives - Waterstream.io | Simplify MQTT Data Integration<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/waterstream.io\/it\/category\/senza-categoria\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Senza categoria Archives - Waterstream.io | Simplify MQTT Data Integration\" \/>\n<meta property=\"og:url\" content=\"https:\/\/waterstream.io\/it\/category\/senza-categoria\/\" \/>\n<meta property=\"og:site_name\" content=\"Waterstream.io | Simplify MQTT Data Integration\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/waterstream.io\\\/it\\\/category\\\/senza-categoria\\\/\",\"url\":\"https:\\\/\\\/waterstream.io\\\/it\\\/category\\\/senza-categoria\\\/\",\"name\":\"Senza categoria Archives - Waterstream.io | Simplify MQTT Data Integration\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/waterstream.io\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/waterstream.io\\\/it\\\/category\\\/senza-categoria\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/waterstream.io\\\/it\\\/category\\\/senza-categoria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/waterstream.io\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Senza categoria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/waterstream.io\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/waterstream.io\\\/it\\\/\",\"name\":\"Waterstream.io | Simplify MQTT Data Integration\",\"description\":\"High performance MQTT Broker\",\"publisher\":{\"@id\":\"https:\\\/\\\/waterstream.io\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/waterstream.io\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/waterstream.io\\\/it\\\/#organization\",\"name\":\"Waterstream.io | Simplify MQTT Data Integration\",\"url\":\"https:\\\/\\\/waterstream.io\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/waterstream.io\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/waterstream.io\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/WaterStream-Logo-Color.png\",\"contentUrl\":\"https:\\\/\\\/waterstream.io\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/WaterStream-Logo-Color.png\",\"width\":500,\"height\":117,\"caption\":\"Waterstream.io | Simplify MQTT Data Integration\"},\"image\":{\"@id\":\"https:\\\/\\\/waterstream.io\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Senza categoria Archives - Waterstream.io | Simplify MQTT Data Integration","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/waterstream.io\/it\/category\/senza-categoria\/","og_locale":"it_IT","og_type":"article","og_title":"Senza categoria Archives - Waterstream.io | Simplify MQTT Data Integration","og_url":"https:\/\/waterstream.io\/it\/category\/senza-categoria\/","og_site_name":"Waterstream.io | Simplify MQTT Data Integration","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/waterstream.io\/it\/category\/senza-categoria\/","url":"https:\/\/waterstream.io\/it\/category\/senza-categoria\/","name":"Senza categoria Archives - Waterstream.io | Simplify MQTT Data Integration","isPartOf":{"@id":"https:\/\/waterstream.io\/it\/#website"},"breadcrumb":{"@id":"https:\/\/waterstream.io\/it\/category\/senza-categoria\/#breadcrumb"},"inLanguage":"it-IT"},{"@type":"BreadcrumbList","@id":"https:\/\/waterstream.io\/it\/category\/senza-categoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/waterstream.io\/it\/"},{"@type":"ListItem","position":2,"name":"Senza categoria"}]},{"@type":"WebSite","@id":"https:\/\/waterstream.io\/it\/#website","url":"https:\/\/waterstream.io\/it\/","name":"Waterstream.io | Simplify MQTT Data Integration","description":"High performance MQTT Broker","publisher":{"@id":"https:\/\/waterstream.io\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/waterstream.io\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/waterstream.io\/it\/#organization","name":"Waterstream.io | Simplify MQTT Data Integration","url":"https:\/\/waterstream.io\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/waterstream.io\/it\/#\/schema\/logo\/image\/","url":"https:\/\/waterstream.io\/wp-content\/uploads\/2022\/05\/WaterStream-Logo-Color.png","contentUrl":"https:\/\/waterstream.io\/wp-content\/uploads\/2022\/05\/WaterStream-Logo-Color.png","width":500,"height":117,"caption":"Waterstream.io | Simplify MQTT Data Integration"},"image":{"@id":"https:\/\/waterstream.io\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/waterstream.io\/it\/wp-json\/wp\/v2\/categories\/118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/waterstream.io\/it\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/waterstream.io\/it\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/waterstream.io\/it\/wp-json\/wp\/v2\/posts?categories=118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}